{"id":670,"count":4,"description":"","link":"https:\/\/www.snowtrex.it\/magazine\/tag\/kufsteinerland\/","name":"Kufsteinerland","slug":"kufsteinerland","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kufsteinerland - SnowTrex sci magazine<\/title>\n<meta name=\"description\" content=\"Kufsteinerland - SnowTrex sci magazine\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kufsteinerland\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.snowtrex.it\/magazine\/tag\/kufsteinerland\/\" \/>\n<meta property=\"og:site_name\" content=\"SnowTrex sci magazine\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.it\\\/tag\\\/kufsteinerland\\\/\",\"url\":\"http:\\\/\\\/wp-magazin.snowtrex.it\\\/tag\\\/kufsteinerland\\\/\",\"name\":\"Kufsteinerland - SnowTrex sci magazine\",\"description\":\"Kufsteinerland - SnowTrex sci magazine\",\"inLanguage\":\"it-IT\"},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.it\\\/#website\",\"url\":\"http:\\\/\\\/wp-magazin.snowtrex.it\\\/\",\"name\":\"SnowTrex sci magazine\",\"description\":\"Tutto su sci, snowboard e vacanze invernali!\",\"publisher\":{\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.it\\\/#organization\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.it\\\/#organization\",\"name\":\"TravelTrex GmbH\",\"url\":\"http:\\\/\\\/wp-magazin.snowtrex.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"TravelTrex GmbH\"},\"image\":{\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SnowTrex.de\\\/\",\"https:\\\/\\\/www.instagram.com\\\/snowtrex_ski\\\/\"],\"description\":\"Dal 1999 SnowTrex \u00e8 il tour operator leader in Germania per le vacanze sulla neve. L'azienda commercializza le sue offerte in 13 lingue e ogni anno porta oltre 100.000 ospiti in destinazioni popolari come Austria, Francia, Italia, Svizzera e Germania.\",\"email\":\"info-it@snowtrex.com\",\"telephone\":\"800 684382\",\"legalName\":\"TravelTrex GmbH\",\"foundingDate\":\"1999-07-01\",\"vatID\":\"DE 813 076 768\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kufsteinerland - SnowTrex sci magazine","description":"Kufsteinerland - SnowTrex sci magazine","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Kufsteinerland","og_url":"https:\/\/www.snowtrex.it\/magazine\/tag\/kufsteinerland\/","og_site_name":"SnowTrex sci magazine","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.snowtrex.it\/magazine\/tag\/kufsteinerland\/","url":"https:\/\/www.snowtrex.it\/magazine\/tag\/kufsteinerland\/","name":"Kufsteinerland - SnowTrex sci magazine","description":"Kufsteinerland - SnowTrex sci magazine","inLanguage":"it-IT"},{"@type":"WebSite","@id":"https:\/\/www.snowtrex.it\/magazine\/#website","url":"https:\/\/www.snowtrex.it\/magazine\/","name":"SnowTrex sci magazine","description":"Tutto su sci, snowboard e vacanze invernali!","publisher":{"@id":"https:\/\/www.snowtrex.it\/magazine\/#organization"},"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.snowtrex.it\/magazine\/#organization","name":"TravelTrex GmbH","url":"https:\/\/www.snowtrex.it\/magazine\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.snowtrex.it\/magazine\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"TravelTrex GmbH"},"image":{"@id":"https:\/\/www.snowtrex.it\/magazine\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SnowTrex.de\/","https:\/\/www.instagram.com\/snowtrex_ski\/"],"description":"Dal 1999 SnowTrex \u00e8 il tour operator leader in Germania per le vacanze sulla neve. L'azienda commercializza le sue offerte in 13 lingue e ogni anno porta oltre 100.000 ospiti in destinazioni popolari come Austria, Francia, Italia, Svizzera e Germania.","email":"info-it@snowtrex.com","telephone":"800 684382","legalName":"TravelTrex GmbH","foundingDate":"1999-07-01","vatID":"DE 813 076 768","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"}}]}},"_links":{"self":[{"href":"https:\/\/www.snowtrex.it\/magazine\/wp-json\/wp\/v2\/tags\/670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.snowtrex.it\/magazine\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.snowtrex.it\/magazine\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.snowtrex.it\/magazine\/wp-json\/wp\/v2\/posts?tags=670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}